{"id":158045,"date":"2025-08-19T04:06:14","date_gmt":"2025-08-19T02:06:14","guid":{"rendered":"https:\/\/lionel-meylan.ch\/produit\/extrait-de-n5-necklace-2\/"},"modified":"2026-08-17T16:01:26","modified_gmt":"2026-08-17T14:01:26","slug":"extrait-de-n5-necklace-2","status":"publish","type":"product","link":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/","title":{"rendered":"Extrait De N\u00b05 Necklace"},"excerpt":{"rendered":"<p>18K BEIGE GOLD, diamonds<\/p>\n","protected":false},"featured_media":128900,"template":"","meta":{"_acf_changed":false},"product_brand":[391],"product_cat":[491,494],"product_tag":[],"product_collection":[1169],"class_list":["post-158045","product","type-product","status-publish","has-post-thumbnail","product_brand-chanel-en","product_cat-new","product_cat-jewellery","product_collection-collection-n5","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":{"product_is_new":false,"product_not_available":false,"product_related_stores":null,"product_infos":"","product_features":null,"product_cta_title":"","product_cta_descr":"","product_cta_btn":null,"product_cta_img":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extrait De N\u00b05 Necklace | Lionel Meylan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extrait De N\u00b05 Necklace | Lionel Meylan\" \/>\n<meta property=\"og:description\" content=\"18K BEIGE GOLD, diamonds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Lionel Meylan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lionelmeylanvevey\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-17T14:01:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/\",\"name\":\"Extrait De N\u00b05 Necklace | Lionel Meylan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png\",\"datePublished\":\"2025-08-19T02:06:14+00:00\",\"dateModified\":\"2026-08-17T14:01:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png\",\"contentUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/extrait-de-n5-necklace-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Extrait De N\u00b05 Necklace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\",\"name\":\"Lionel Meylan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#organization\",\"name\":\"Lionel Meylan\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo..svg\",\"contentUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo..svg\",\"caption\":\"Lionel Meylan\"},\"image\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lionelmeylanvevey\",\"https:\\\/\\\/www.instagram.com\\\/lionel_meylan\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10324373\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extrait De N\u00b05 Necklace | Lionel Meylan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/","og_locale":"en_US","og_type":"article","og_title":"Extrait De N\u00b05 Necklace | Lionel Meylan","og_description":"18K BEIGE GOLD, diamonds","og_url":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/","og_site_name":"Lionel Meylan","article_publisher":"https:\/\/www.facebook.com\/lionelmeylanvevey","article_modified_time":"2026-08-17T14:01:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/","url":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/","name":"Extrait De N\u00b05 Necklace | Lionel Meylan","isPartOf":{"@id":"https:\/\/lionel-meylan.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/#primaryimage"},"image":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/#primaryimage"},"thumbnailUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2025\/08\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png","datePublished":"2025-08-19T02:06:14+00:00","dateModified":"2026-08-17T14:01:26+00:00","breadcrumb":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/#primaryimage","url":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2025\/08\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png","contentUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2025\/08\/apm0rfw0nmy4ccjyfp7l2f02f5b2268deefee194eb7b8565ec8a1ba03..png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/lionel-meylan.ch\/en\/product\/extrait-de-n5-necklace-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lionel-meylan.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/lionel-meylan.ch\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Extrait De N\u00b05 Necklace"}]},{"@type":"WebSite","@id":"https:\/\/lionel-meylan.ch\/en\/#website","url":"https:\/\/lionel-meylan.ch\/en\/","name":"Lionel Meylan","description":"","publisher":{"@id":"https:\/\/lionel-meylan.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lionel-meylan.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lionel-meylan.ch\/en\/#organization","name":"Lionel Meylan","url":"https:\/\/lionel-meylan.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lionel-meylan.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2024\/09\/logo..svg","contentUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2024\/09\/logo..svg","caption":"Lionel Meylan"},"image":{"@id":"https:\/\/lionel-meylan.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lionelmeylanvevey","https:\/\/www.instagram.com\/lionel_meylan\/","https:\/\/www.linkedin.com\/company\/10324373"]}]}},"_links":{"self":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product\/158045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/media\/128900"}],"wp:attachment":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/media?parent=158045"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_brand?post=158045"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_cat?post=158045"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_tag?post=158045"},{"taxonomy":"product_collection","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_collection?post=158045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}