{"id":206573,"date":"2026-04-24T03:29:37","date_gmt":"2026-04-24T01:29:37","guid":{"rendered":"https:\/\/lionel-meylan.ch\/produit\/silver-mini-granelli-bracelet\/"},"modified":"2026-09-02T03:29:21","modified_gmt":"2026-09-02T01:29:21","slug":"silver-mini-granelli-bracelet","status":"publish","type":"product","link":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/","title":{"rendered":"Silver Mini Granelli Bracelet"},"excerpt":{"rendered":"<p>The shimmer of sand sparkles in the Granelli collection! <br \/>Jewels for adding to and collecting as you dream of sun-drenched beaches\u2026 then why not take a plunge into the colours of the sea with the creations in turquoise or blue ceramic?<\/p>\n<p>Bracciale mini Granelli in argento 925 con catena in acciaio, t-bar in argento e anello bris\u00e8 in oro giallo 9K. Piastrine in argento e acciaio. Ago in acciaio incluso.<\/p>\n","protected":false},"featured_media":155939,"template":"","meta":{"_acf_changed":false},"product_brand":[403],"product_cat":[491,494],"product_tag":[],"product_collection":[],"class_list":["post-206573","product","type-product","status-publish","has-post-thumbnail","product_brand-dodo-en","product_cat-new","product_cat-jewellery","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":{"product_is_new":false,"product_not_available":false,"product_related_stores":null,"product_infos":"","product_features":null,"product_cta_title":"","product_cta_descr":"","product_cta_btn":null,"product_cta_img":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Silver Mini Granelli Bracelet | Lionel Meylan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Silver Mini Granelli Bracelet | Lionel Meylan\" \/>\n<meta property=\"og:description\" content=\"The shimmer of sand sparkles in the Granelli collection! Jewels for adding to and collecting as you dream of sun-drenched beaches\u2026 then why not take a plunge into the colours of the sea with the creations in turquoise or blue ceramic?Bracciale mini Granelli in argento 925 con catena in acciaio, t-bar in argento e anello bris\u00e8 in oro giallo 9K. Piastrine in argento e acciaio. Ago in acciaio incluso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/\" \/>\n<meta property=\"og:site_name\" content=\"Lionel Meylan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lionelmeylanvevey\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T01:29:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/\",\"name\":\"Silver Mini Granelli Bracelet | Lionel Meylan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png\",\"datePublished\":\"2026-04-24T01:29:37+00:00\",\"dateModified\":\"2026-09-02T01:29:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png\",\"contentUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/product\\\/silver-mini-granelli-bracelet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Silver Mini Granelli Bracelet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\",\"name\":\"Lionel Meylan\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#organization\",\"name\":\"Lionel Meylan\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo..svg\",\"contentUrl\":\"https:\\\/\\\/lionel-meylan.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo..svg\",\"caption\":\"Lionel Meylan\"},\"image\":{\"@id\":\"https:\\\/\\\/lionel-meylan.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lionelmeylanvevey\",\"https:\\\/\\\/www.instagram.com\\\/lionel_meylan\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/10324373\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Silver Mini Granelli Bracelet | Lionel Meylan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/","og_locale":"en_US","og_type":"article","og_title":"Silver Mini Granelli Bracelet | Lionel Meylan","og_description":"The shimmer of sand sparkles in the Granelli collection! Jewels for adding to and collecting as you dream of sun-drenched beaches\u2026 then why not take a plunge into the colours of the sea with the creations in turquoise or blue ceramic?Bracciale mini Granelli in argento 925 con catena in acciaio, t-bar in argento e anello bris\u00e8 in oro giallo 9K. Piastrine in argento e acciaio. Ago in acciaio incluso.","og_url":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/","og_site_name":"Lionel Meylan","article_publisher":"https:\/\/www.facebook.com\/lionelmeylanvevey","article_modified_time":"2026-09-02T01:29:21+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/","url":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/","name":"Silver Mini Granelli Bracelet | Lionel Meylan","isPartOf":{"@id":"https:\/\/lionel-meylan.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/#primaryimage"},"image":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/#primaryimage"},"thumbnailUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2026\/04\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png","datePublished":"2026-04-24T01:29:37+00:00","dateModified":"2026-09-02T01:29:21+00:00","breadcrumb":{"@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/#primaryimage","url":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2026\/04\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png","contentUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2026\/04\/1ix52sleoifde5kzganh2f02fd41696e033b78ed79a42aacd48eff554..png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/lionel-meylan.ch\/en\/product\/silver-mini-granelli-bracelet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/lionel-meylan.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/lionel-meylan.ch\/en\/store\/"},{"@type":"ListItem","position":3,"name":"Silver Mini Granelli Bracelet"}]},{"@type":"WebSite","@id":"https:\/\/lionel-meylan.ch\/en\/#website","url":"https:\/\/lionel-meylan.ch\/en\/","name":"Lionel Meylan","description":"","publisher":{"@id":"https:\/\/lionel-meylan.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lionel-meylan.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lionel-meylan.ch\/en\/#organization","name":"Lionel Meylan","url":"https:\/\/lionel-meylan.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lionel-meylan.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2024\/09\/logo..svg","contentUrl":"https:\/\/lionel-meylan.ch\/wp-content\/uploads\/2024\/09\/logo..svg","caption":"Lionel Meylan"},"image":{"@id":"https:\/\/lionel-meylan.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lionelmeylanvevey","https:\/\/www.instagram.com\/lionel_meylan\/","https:\/\/www.linkedin.com\/company\/10324373"]}]}},"_links":{"self":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product\/206573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/media\/155939"}],"wp:attachment":[{"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/media?parent=206573"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_brand?post=206573"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_cat?post=206573"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_tag?post=206573"},{"taxonomy":"product_collection","embeddable":true,"href":"https:\/\/lionel-meylan.ch\/en\/wp-json\/wp\/v2\/product_collection?post=206573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}